{"id":212339,"date":"2026-01-30T10:01:22","date_gmt":"2026-01-30T09:01:22","guid":{"rendered":"https:\/\/uchitomishop.ch\/produit\/jun-curry-powder-hachi-13g\/"},"modified":"2026-06-02T14:08:37","modified_gmt":"2026-06-02T12:08:37","slug":"jun-curry-powder-hachi-13g","status":"publish","type":"product","link":"https:\/\/uchitomishop.ch\/de\/produkt\/jun-curry-powder-hachi-13g\/","title":{"rendered":"JUN CURRY POWDER &#171;HACHI&#187; 13G"},"content":{"rendered":"<p>Currypulver, ideal f\u00fcr Currys, sautierte Gerichte, Pilaw, Nudeln usw.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Currypulver, ideal f\u00fcr Currys, sautierte Gerichte, Pilaw, Nudeln usw.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[571,444,478],"product_tag":[],"class_list":["post-212339","product","type-product","status-publish","product_cat-gewurze","product_cat-lebensmittel","product_cat-wurzen-gewurze","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JUN CURRY POWDER &quot;HACHI&quot; 13G - Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uchitomishop.ch\/de\/produkt\/jun-curry-powder-hachi-13g\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JUN CURRY POWDER &quot;HACHI&quot; 13G - Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz\" \/>\n<meta property=\"og:description\" content=\"Currypulver, ideal f\u00fcr Currys, sautierte Gerichte, Pilaw, Nudeln usw.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uchitomishop.ch\/de\/produkt\/jun-curry-powder-hachi-13g\/\" \/>\n<meta property=\"og:site_name\" content=\"Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T12:08:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uchitomishop.ch\/wp-content\/uploads\/2026\/05\/4902688011155.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"304\" \/>\n\t<meta property=\"og:image:height\" content=\"282\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/produkt\\\/jun-curry-powder-hachi-13g\\\/\",\"url\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/produkt\\\/jun-curry-powder-hachi-13g\\\/\",\"name\":\"JUN CURRY POWDER \\\"HACHI\\\" 13G - Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/#website\"},\"datePublished\":\"2026-01-30T09:01:22+00:00\",\"dateModified\":\"2026-06-02T12:08:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/produkt\\\/jun-curry-powder-hachi-13g\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/produkt\\\/jun-curry-powder-hachi-13g\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/produkt\\\/jun-curry-powder-hachi-13g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JUN CURRY POWDER \u00ab\u00a0HACHI\u00a0\u00bb 13G\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/\",\"name\":\"Uchitomishop - Magasin en ligne Japonais - Livraison dans toute la Suisse\",\"description\":\"Japanisches Online-Gesch\u00e4ft. Entdecken Sie alle unsere japanischen Produkte: Lebensmittel, K\u00fcche, B\u00fccher, Haushalt, Schreibwaren, Pflege, Textilien und Geschirr. Lieferung in der gesamten Schweiz.\",\"publisher\":{\"@id\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/#organization\",\"name\":\"Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz\",\"url\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uchitomishop.ch\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/uchitomishop.ch\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo.png\",\"width\":380,\"height\":162,\"caption\":\"Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz\"},\"image\":{\"@id\":\"https:\\\/\\\/uchitomishop.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JUN CURRY POWDER \"HACHI\" 13G - Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uchitomishop.ch\/de\/produkt\/jun-curry-powder-hachi-13g\/","og_locale":"de_DE","og_type":"article","og_title":"JUN CURRY POWDER \"HACHI\" 13G - Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz","og_description":"Currypulver, ideal f\u00fcr Currys, sautierte Gerichte, Pilaw, Nudeln usw.","og_url":"https:\/\/uchitomishop.ch\/de\/produkt\/jun-curry-powder-hachi-13g\/","og_site_name":"Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz","article_modified_time":"2026-06-02T12:08:37+00:00","og_image":[{"width":304,"height":282,"url":"https:\/\/uchitomishop.ch\/wp-content\/uploads\/2026\/05\/4902688011155.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uchitomishop.ch\/de\/produkt\/jun-curry-powder-hachi-13g\/","url":"https:\/\/uchitomishop.ch\/de\/produkt\/jun-curry-powder-hachi-13g\/","name":"JUN CURRY POWDER \"HACHI\" 13G - Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz","isPartOf":{"@id":"https:\/\/uchitomishop.ch\/de\/#website"},"datePublished":"2026-01-30T09:01:22+00:00","dateModified":"2026-06-02T12:08:37+00:00","breadcrumb":{"@id":"https:\/\/uchitomishop.ch\/de\/produkt\/jun-curry-powder-hachi-13g\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uchitomishop.ch\/de\/produkt\/jun-curry-powder-hachi-13g\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/uchitomishop.ch\/de\/produkt\/jun-curry-powder-hachi-13g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/uchitomishop.ch\/de\/homepage\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/uchitomishop.ch\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"JUN CURRY POWDER \u00ab\u00a0HACHI\u00a0\u00bb 13G"}]},{"@type":"WebSite","@id":"https:\/\/uchitomishop.ch\/de\/#website","url":"https:\/\/uchitomishop.ch\/de\/","name":"Uchitomishop - Magasin en ligne Japonais - Livraison dans toute la Suisse","description":"Japanisches Online-Gesch\u00e4ft. Entdecken Sie alle unsere japanischen Produkte: Lebensmittel, K\u00fcche, B\u00fccher, Haushalt, Schreibwaren, Pflege, Textilien und Geschirr. Lieferung in der gesamten Schweiz.","publisher":{"@id":"https:\/\/uchitomishop.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uchitomishop.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/uchitomishop.ch\/de\/#organization","name":"Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz","url":"https:\/\/uchitomishop.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/uchitomishop.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/uchitomishop.ch\/wp-content\/uploads\/2024\/04\/logo.png","contentUrl":"https:\/\/uchitomishop.ch\/wp-content\/uploads\/2024\/04\/logo.png","width":380,"height":162,"caption":"Uchitomishop - Japanischer Online-Shop - Lieferung in die ganze Schweiz"},"image":{"@id":"https:\/\/uchitomishop.ch\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/uchitomishop.ch\/de\/wp-json\/wp\/v2\/product\/212339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uchitomishop.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/uchitomishop.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/uchitomishop.ch\/de\/wp-json\/wp\/v2\/comments?post=212339"}],"wp:attachment":[{"href":"https:\/\/uchitomishop.ch\/de\/wp-json\/wp\/v2\/media?parent=212339"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/uchitomishop.ch\/de\/wp-json\/wp\/v2\/product_brand?post=212339"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/uchitomishop.ch\/de\/wp-json\/wp\/v2\/product_cat?post=212339"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/uchitomishop.ch\/de\/wp-json\/wp\/v2\/product_tag?post=212339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}